{"id":1777,"date":"2022-10-27T16:11:10","date_gmt":"2022-10-27T12:11:10","guid":{"rendered":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/?p=1777"},"modified":"2022-10-27T16:11:11","modified_gmt":"2022-10-27T12:11:11","slug":"aqprfa-120-jus-detox-frais","status":"publish","type":"post","link":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2022\/10\/27\/aqprfa-120-jus-detox-frais\/","title":{"rendered":"AQPrFa 120 : jus d\u00e9tox frais"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/files\/2022\/10\/AQPrFa-120-V1-jus-detox-SP4.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ouvrir en pdf<\/a><\/strong><\/p>\n\n\n\n<p>On veut pr\u00e9parer au moins 5 litres de jus frais, \u00e0 base de pommes et de c\u00e9leri.<\/p>\n\n\n\n<p><strong><u>1- Formulation en pourcentage&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Produits<\/strong><\/td><td><strong>Quantit\u00e9<\/strong><\/td><\/tr><tr><td>Jus de fruits et l\u00e9gumes<\/td><td>100%<\/td><\/tr><tr><td><em>Dont pommes 80%, tiges de c\u00e9leri 20% (calcul\u00e9 sur les masses avant broyage)<\/em><\/td><td>&nbsp;<\/td><\/tr><tr><td>Conditionnement&nbsp;:<\/td><td>Bouteilles en verre de 0,75 L<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<ul><li>Faire le calcul de la masse minimum \u00e0 peser de fruits sachant que le rendement de la fabrication d\u2019un jus est voisin de 50 L de jus \/ 100 Kg de fruits ou l\u00e9gumes frais.<\/li><\/ul>\n\n\n\n<ul><li>V\u00e9rifier la disponibilit\u00e9 de toutes les mati\u00e8res premi\u00e8res (articles de conditionnement compris).<\/li><li>V\u00e9rifier la conformit\u00e9 des mati\u00e8res premi\u00e8res et des articles de conditionnement selon\u00a0<strong><a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/16\/aqprecf-02-controle-de-masse-des-articles-de-conditionnement\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrECF 02<\/a><\/strong>.<\/li><\/ul>\n\n\n\n<p><strong><u>2- Protocole de fabrication&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<ul><li>Peser les fruits.<\/li><li>Pr\u00e9parer les articles de conditionnement et le mat\u00e9riel n\u00e9cessaire.<\/li><li><strong><em>Assurez-vous que toute la chaine de production soit pr\u00eate avant de commencer, afin de minimiser le temps d\u2019oxydation du jus apr\u00e8s broyage.<\/em><\/strong><\/li><\/ul>\n\n\n\n<ul><li>Laver les fruits et l\u00e9gumes \u00e0 la main.<\/li><li>Couper les c\u00e9leris afin de ne conserver que les branches (aussi appel\u00e9es tiges)<\/li><li>Broyer les pommes et le c\u00e9leri au broyeur \u00e0 couteaux  (<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/12\/aqprma-54-broyeur-a-couteaux\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrMa 54<\/a>), en un seul lot.<\/li><li>Extraire le jus de la pulpe obtenue \u00e0 l\u2019aide de la presse \u00e0 paquet (<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/13\/aqprma-52-presse-a-paquets\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrMa 52<\/a>). En principe, une seule toile suffit pour la quantit\u00e9 de pulpe.<\/li><li>Transf\u00e9rer le jus dans des bouteilles en verre \u00e0 l\u2019aide d\u2019un entonnoir, \u00e0 raison de 700g\/bouteille.<\/li><li>Capsuler les bouteilles (<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/13\/aqprma-56-capsuleuse\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrMa 56<\/a>).<\/li><li>Refroidir les bouteilles dans la cellule de refroidissement (<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/12\/aqprma-21-cellule-de-refroidissement\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrMa 21<\/a>) pendant 15 minutes sur r\u00e9glage \u00ab\u00a0maximum\u00a0\u00bb.<\/li><li>Etiqueter.<\/li><li>Stocker \u00e0 4\u00b0C<\/li><li>Effectuer les contr\u00f4les sur le produit fini.\u00a0\u00a0\u00a0\u00a0\u00a0<\/li><\/ul>\n\n\n\n<p><strong><u>3- Contr\u00f4les produit fini&nbsp;:<\/u><\/strong><\/p>\n\n\n\n<ul><li>Appliquer les proc\u00e9dures de contr\u00f4les PF suivantes\u00a0:<ul><li>Mesure de la viscosit\u00e9 selon\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/08\/03\/aqprpf-04-controle-de-viscosite\/\" target=\"_blank\">AQPrPF 04<\/a>.<\/li><\/ul><ul><li>Mesure du pH selon\u00a0<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/30\/aqprpf-06-controle-du-ph\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrPF 06<\/a>.<\/li><\/ul><ul><li>Mesure de la densit\u00e9\u00a0\u00a0selon <a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/31\/aqprpf-11-mesure-de-densite\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrPF 11<\/a>.<\/li><\/ul><ul><li>Mesure du taux de sucre \u00e0 l\u2019aide du r\u00e9fractom\u00e8tre\u00a0(<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/12\/aqprma-29-refractometre-digital\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrMa 29<\/a>)<\/li><\/ul><ul><li>Analyse sensorielle d\u2019un jus selon\u00a0<a href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2020\/07\/31\/aqprpf-20-analyse-sensorielle-dun-jus-frais\/\" target=\"_blank\" rel=\"noreferrer noopener\">AQPrPF 20<\/a>.<\/li><\/ul><\/li><\/ul>\n\n\n\n<ul><li>Conclure sur la conformit\u00e9 du produit&nbsp;:<ul><li>Compl\u00e9ter la fiche conformit\u00e9 (fiche contr\u00f4les produit fini en pr\u00e9cisant les valeurs des r\u00e9sultats obtenus),<\/li><\/ul><ul><li>D\u00e9finir une DLC de 24 heures.<\/li><\/ul><ul><li>Si besoin faire une fiche de refus de lot.<\/li><\/ul><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ouvrir en pdf On veut pr\u00e9parer au moins 5 litres de jus frais, \u00e0 base de pommes et de c\u00e9leri. 1- Formulation en pourcentage&nbsp;: Produits Quantit\u00e9 Jus de fruits et l\u00e9gumes 100% Dont pommes 80%, tiges de c\u00e9leri 20% (calcul\u00e9 sur les masses avant broyage) &nbsp; Conditionnement&nbsp;: Bouteilles en verre&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/2022\/10\/27\/aqprfa-120-jus-detox-frais\/\"> Continue reading <span class=\"meta-nav\">&rarr; <\/span><\/a><\/p>\n","protected":false},"author":473,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_links_to":"","_links_to_target":""},"categories":[11],"tags":[423,424,241],"_links":{"self":[{"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/posts\/1777"}],"collection":[{"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/users\/473"}],"replies":[{"embeddable":true,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/comments?post=1777"}],"version-history":[{"count":1,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/posts\/1777\/revisions"}],"predecessor-version":[{"id":1779,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/posts\/1777\/revisions\/1779"}],"wp:attachment":[{"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/media?parent=1777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/categories?post=1777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portail.stpaul4.ac-reunion.fr\/wordpress\/process\/wp-json\/wp\/v2\/tags?post=1777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}